{"id":21,"date":"2016-02-03T16:54:41","date_gmt":"2016-02-03T15:54:41","guid":{"rendered":"http:\/\/localhost\/donmar\/?p=21"},"modified":"2016-07-05T18:54:32","modified_gmt":"2016-07-05T17:54:32","slug":"comme-tous-les-matins","status":"publish","type":"post","link":"http:\/\/www.donmar.fr\/index.php\/2016\/02\/03\/comme-tous-les-matins\/","title":{"rendered":"Comme tous les matins"},"content":{"rendered":"<p><em>Tous les matins au petit jour,<br \/>\nJ\u2019exhume mes r\u00eaveries,<br \/>\nEt me perd ainsi dans l\u2019oubli<br \/>\nTous les matins, dans la basse-cour.<\/em><\/p>\n<p>Comme tous les matins m\u2019en allant sur le quai,<br \/>\nDans un jeu de sape, je m\u2019en vais m\u2019enquiller,<br \/>\nLes yeux sur le bitume \u00e0 ruminer l\u2019ennui,<br \/>\nBouff\u00e9 par l\u2019amertume et la m\u00e9lancolie.<\/p>\n<p>Viens mon paquebot dans un fracas d\u2019enfer<br \/>\nEnserrer nos \u00e2mes dans ses m\u00e2choires de fer<br \/>\nLe temps d\u2019une journ\u00e9e et puis le soir venu<br \/>\nLes recracher vides ou pleines d\u2019espoirs d\u00e9\u00e7us.<\/p>\n<p><em>Tous les matins au petit jour,<br \/>\nJ\u2019exhume mes r\u00eaveries,<br \/>\nEt me perd ainsi dans l\u2019oubli<br \/>\nTous les matins, dans la basse-cour.<\/em><\/p>\n<p>Soudain dans la grisaille des visages harass\u00e9s,<br \/>\nS\u2019esquissent les contours d\u2019une jolie poup\u00e9e<br \/>\nEt mon \u00e2me s\u2019arrime \u00e0 ses yeux d\u00e9licats<br \/>\nCern\u00e9s de regards et de Mascara.<\/p>\n<p>Quand nos regards las, d\u2019un \u00e9lan solidaire<br \/>\nS\u2019enlacent l\u2019espace d\u2019un silence lapidaire<br \/>\nJ\u2019ai les sangs qui chavirent et le c\u0153ur en d\u00e9rive<br \/>\nBringuebal\u00e9 d\u2019amours mortes que ses yeux d\u2019encre ravivent.<\/p>\n<p>Me voil\u00e0 pris, je suis pi\u00e9g\u00e9<br \/>\nDans l\u2019ivresse d\u2019un brouillon<br \/>\nDe f\u00e9licit\u00e9.<br \/>\nD\u00e9j\u00e0 je me sens m\u2019\u00e9garer<br \/>\nDans la chaleur de son \u00e9treinte<br \/>\nJe suis poss\u00e9d\u00e9.<\/p>\n<p><em>Et ce matin au petit jour,<br \/>\nJ\u2019enterre mes r\u00eaveries,<br \/>\nEt m\u2019abandonne ainsi \u00e0 l\u2019oubli<br \/>\nComme ce matin, comme par amour.<\/em><\/p>\n<p>Mais sans crier gare et d\u2019une humeur irrit\u00e9e<br \/>\nVoil\u00e0 qu\u2019elle se d\u00e9tourne et feint de m\u2019ignorer<br \/>\nNe me laissant plus, comme espoir en souffrance,<br \/>\nQu\u2019\u00e0 nouveau m\u00e9pris et indiff\u00e9rence.<\/p>\n<p>Comme tous les matins m\u2019en allant sur le quai,<br \/>\nLe c\u0153ur dans les vapes, je m\u2019en vais m\u2019oublier,<br \/>\nLes yeux sur le bitume \u00e0 ennuyer l\u2019ennui,<br \/>\nBouff\u00e9 par l\u2019amertume et la m\u00e9lancolie.<\/p>\n<p><em>Tous les matins au petit jour,<br \/>\nJ\u2019exhume mes r\u00eaveries,<br \/>\nEt me perd ainsi dans l\u2019oubli<br \/>\nTous les matins, dans la basse-cour.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tous les matins au petit jour, J\u2019exhume mes r\u00eaveries, Et[&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":246,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-21","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chanson"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comme tous les matins - Le blog de DonMar<\/title>\n<meta name=\"description\" content=\"Bienvenue sur le blog de DonMar, parolier et auteur.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.donmar.fr\/index.php\/2016\/02\/03\/comme-tous-les-matins\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comme tous les matins - Le blog de DonMar\" \/>\n<meta property=\"og:description\" content=\"Bienvenue sur le blog de DonMar, parolier et auteur.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.donmar.fr\/index.php\/2016\/02\/03\/comme-tous-les-matins\/\" \/>\n<meta property=\"og:site_name\" content=\"Le blog de DonMar\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-03T15:54:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-05T17:54:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.donmar.fr\/wp-content\/uploads\/2016\/07\/Comme-tous-les-matins-e1467827452968.jpg?fit=960%2C379&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"379\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"DonMar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"DonMar\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.donmar.fr\\\/index.php\\\/2016\\\/02\\\/03\\\/comme-tous-les-matins\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.donmar.fr\\\/index.php\\\/2016\\\/02\\\/03\\\/comme-tous-les-matins\\\/\"},\"author\":{\"name\":\"DonMar\",\"@id\":\"https:\\\/\\\/www.donmar.fr\\\/#\\\/schema\\\/person\\\/c4d37006b66e1ec7bb1cca42fce0e19a\"},\"headline\":\"Comme tous les matins\",\"datePublished\":\"2016-02-03T15:54:41+00:00\",\"dateModified\":\"2016-07-05T17:54:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.donmar.fr\\\/index.php\\\/2016\\\/02\\\/03\\\/comme-tous-les-matins\\\/\"},\"wordCount\":352,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.donmar.fr\\\/index.php\\\/2016\\\/02\\\/03\\\/comme-tous-les-matins\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.donmar.fr\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/Comme-tous-les-matins-e1467827452968.jpg?fit=960%2C379\",\"articleSection\":[\"Chanson\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.donmar.fr\\\/index.php\\\/2016\\\/02\\\/03\\\/comme-tous-les-matins\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.donmar.fr\\\/index.php\\\/2016\\\/02\\\/03\\\/comme-tous-les-matins\\\/\",\"url\":\"https:\\\/\\\/www.donmar.fr\\\/index.php\\\/2016\\\/02\\\/03\\\/comme-tous-les-matins\\\/\",\"name\":\"Comme tous les matins - Le blog de DonMar\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.donmar.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.donmar.fr\\\/index.php\\\/2016\\\/02\\\/03\\\/comme-tous-les-matins\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.donmar.fr\\\/index.php\\\/2016\\\/02\\\/03\\\/comme-tous-les-matins\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.donmar.fr\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/Comme-tous-les-matins-e1467827452968.jpg?fit=960%2C379\",\"datePublished\":\"2016-02-03T15:54:41+00:00\",\"dateModified\":\"2016-07-05T17:54:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.donmar.fr\\\/#\\\/schema\\\/person\\\/c4d37006b66e1ec7bb1cca42fce0e19a\"},\"description\":\"Bienvenue sur le blog de DonMar, parolier et auteur.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.donmar.fr\\\/index.php\\\/2016\\\/02\\\/03\\\/comme-tous-les-matins\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.donmar.fr\\\/index.php\\\/2016\\\/02\\\/03\\\/comme-tous-les-matins\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.donmar.fr\\\/index.php\\\/2016\\\/02\\\/03\\\/comme-tous-les-matins\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.donmar.fr\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/Comme-tous-les-matins-e1467827452968.jpg?fit=960%2C379\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.donmar.fr\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/Comme-tous-les-matins-e1467827452968.jpg?fit=960%2C379\",\"width\":960,\"height\":379},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.donmar.fr\\\/index.php\\\/2016\\\/02\\\/03\\\/comme-tous-les-matins\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.donmar.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comme tous les matins\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.donmar.fr\\\/#website\",\"url\":\"https:\\\/\\\/www.donmar.fr\\\/\",\"name\":\"Le blog de DonMar\",\"description\":\"Auteur amateur et parolier du dimanche\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.donmar.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.donmar.fr\\\/#\\\/schema\\\/person\\\/c4d37006b66e1ec7bb1cca42fce0e19a\",\"name\":\"DonMar\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0aedcc72186b63121365533ce86a2b74d33031e20475798d13c7d6a044773ad?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0aedcc72186b63121365533ce86a2b74d33031e20475798d13c7d6a044773ad?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0aedcc72186b63121365533ce86a2b74d33031e20475798d13c7d6a044773ad?s=96&d=mm&r=g\",\"caption\":\"DonMar\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comme tous les matins - Le blog de DonMar","description":"Bienvenue sur le blog de DonMar, parolier et auteur.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.donmar.fr\/index.php\/2016\/02\/03\/comme-tous-les-matins\/","og_locale":"fr_FR","og_type":"article","og_title":"Comme tous les matins - Le blog de DonMar","og_description":"Bienvenue sur le blog de DonMar, parolier et auteur.","og_url":"https:\/\/www.donmar.fr\/index.php\/2016\/02\/03\/comme-tous-les-matins\/","og_site_name":"Le blog de DonMar","article_published_time":"2016-02-03T15:54:41+00:00","article_modified_time":"2016-07-05T17:54:32+00:00","og_image":[{"width":960,"height":379,"url":"https:\/\/i0.wp.com\/www.donmar.fr\/wp-content\/uploads\/2016\/07\/Comme-tous-les-matins-e1467827452968.jpg?fit=960%2C379&ssl=1","type":"image\/jpeg"}],"author":"DonMar","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"DonMar","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.donmar.fr\/index.php\/2016\/02\/03\/comme-tous-les-matins\/#article","isPartOf":{"@id":"https:\/\/www.donmar.fr\/index.php\/2016\/02\/03\/comme-tous-les-matins\/"},"author":{"name":"DonMar","@id":"https:\/\/www.donmar.fr\/#\/schema\/person\/c4d37006b66e1ec7bb1cca42fce0e19a"},"headline":"Comme tous les matins","datePublished":"2016-02-03T15:54:41+00:00","dateModified":"2016-07-05T17:54:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.donmar.fr\/index.php\/2016\/02\/03\/comme-tous-les-matins\/"},"wordCount":352,"commentCount":0,"image":{"@id":"https:\/\/www.donmar.fr\/index.php\/2016\/02\/03\/comme-tous-les-matins\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.donmar.fr\/wp-content\/uploads\/2016\/07\/Comme-tous-les-matins-e1467827452968.jpg?fit=960%2C379","articleSection":["Chanson"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.donmar.fr\/index.php\/2016\/02\/03\/comme-tous-les-matins\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.donmar.fr\/index.php\/2016\/02\/03\/comme-tous-les-matins\/","url":"https:\/\/www.donmar.fr\/index.php\/2016\/02\/03\/comme-tous-les-matins\/","name":"Comme tous les matins - Le blog de DonMar","isPartOf":{"@id":"https:\/\/www.donmar.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.donmar.fr\/index.php\/2016\/02\/03\/comme-tous-les-matins\/#primaryimage"},"image":{"@id":"https:\/\/www.donmar.fr\/index.php\/2016\/02\/03\/comme-tous-les-matins\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.donmar.fr\/wp-content\/uploads\/2016\/07\/Comme-tous-les-matins-e1467827452968.jpg?fit=960%2C379","datePublished":"2016-02-03T15:54:41+00:00","dateModified":"2016-07-05T17:54:32+00:00","author":{"@id":"https:\/\/www.donmar.fr\/#\/schema\/person\/c4d37006b66e1ec7bb1cca42fce0e19a"},"description":"Bienvenue sur le blog de DonMar, parolier et auteur.","breadcrumb":{"@id":"https:\/\/www.donmar.fr\/index.php\/2016\/02\/03\/comme-tous-les-matins\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.donmar.fr\/index.php\/2016\/02\/03\/comme-tous-les-matins\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.donmar.fr\/index.php\/2016\/02\/03\/comme-tous-les-matins\/#primaryimage","url":"https:\/\/i0.wp.com\/www.donmar.fr\/wp-content\/uploads\/2016\/07\/Comme-tous-les-matins-e1467827452968.jpg?fit=960%2C379","contentUrl":"https:\/\/i0.wp.com\/www.donmar.fr\/wp-content\/uploads\/2016\/07\/Comme-tous-les-matins-e1467827452968.jpg?fit=960%2C379","width":960,"height":379},{"@type":"BreadcrumbList","@id":"https:\/\/www.donmar.fr\/index.php\/2016\/02\/03\/comme-tous-les-matins\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.donmar.fr\/"},{"@type":"ListItem","position":2,"name":"Comme tous les matins"}]},{"@type":"WebSite","@id":"https:\/\/www.donmar.fr\/#website","url":"https:\/\/www.donmar.fr\/","name":"Le blog de DonMar","description":"Auteur amateur et parolier du dimanche","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.donmar.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.donmar.fr\/#\/schema\/person\/c4d37006b66e1ec7bb1cca42fce0e19a","name":"DonMar","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/e0aedcc72186b63121365533ce86a2b74d33031e20475798d13c7d6a044773ad?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e0aedcc72186b63121365533ce86a2b74d33031e20475798d13c7d6a044773ad?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e0aedcc72186b63121365533ce86a2b74d33031e20475798d13c7d6a044773ad?s=96&d=mm&r=g","caption":"DonMar"}}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.donmar.fr\/wp-content\/uploads\/2016\/07\/Comme-tous-les-matins-e1467827452968.jpg?fit=960%2C379","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":284,"url":"http:\/\/www.donmar.fr\/index.php\/2016\/09\/06\/scene-saint-louis-style\/","url_meta":{"origin":21,"position":0},"title":"Sc\u00e8ne Saint-Louis Style","author":"DonMar","date":"6 septembre 2016","format":false,"excerpt":"Sweet little sixty Reine de toutes les partys Madone post-teenage, toutes les nuits live onstage Je titille les fleurs Du mal en apesanteur Jusqu\u2019\u00e0 l\u2019embolie, je suis votre \u00e9g\u00e9rie Votre muse, Entendez l\u2019ang\u00e9lus, Pour qui sonne le glas, s\u00fbrement pas pour moi. Sc\u00e8ne Saint-Louis Style Ca fuse c'est frontal Toutes\u2026","rel":"","context":"Dans &quot;Chanson&quot;","block_context":{"text":"Chanson","link":"http:\/\/www.donmar.fr\/index.php\/category\/chanson\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.donmar.fr\/wp-content\/uploads\/2016\/09\/Scene-St-Louis-Style.jpg?fit=1200%2C585&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.donmar.fr\/wp-content\/uploads\/2016\/09\/Scene-St-Louis-Style.jpg?fit=1200%2C585&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.donmar.fr\/wp-content\/uploads\/2016\/09\/Scene-St-Louis-Style.jpg?fit=1200%2C585&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.donmar.fr\/wp-content\/uploads\/2016\/09\/Scene-St-Louis-Style.jpg?fit=1200%2C585&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.donmar.fr\/wp-content\/uploads\/2016\/09\/Scene-St-Louis-Style.jpg?fit=1200%2C585&resize=1050%2C600 3x"},"classes":[]},{"id":25,"url":"http:\/\/www.donmar.fr\/index.php\/2016\/02\/03\/crise-de-funambulisme\/","url_meta":{"origin":21,"position":1},"title":"Crise de funambulisme","author":"DonMar","date":"3 f\u00e9vrier 2016","format":false,"excerpt":"Aux quatre coins du monde, d\u2019une \u00e2me vagabonde Au loin je voudrais barouder Enfiler mon galure, partir \u00e0 l\u2019aventure Tout de suite sans me retourner. Squatter les halls de gare, et les a\u00e9rogares Deviendrait alors mon quotidien Vivre dans le surnombre, tout au milieu des ombres Dans un continuel va-et-vient.\u2026","rel":"","context":"Dans &quot;Chanson&quot;","block_context":{"text":"Chanson","link":"http:\/\/www.donmar.fr\/index.php\/category\/chanson\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.donmar.fr\/wp-content\/uploads\/2016\/07\/Crise-de-funambulisme-e1467744137225.jpg?fit=1200%2C473&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.donmar.fr\/wp-content\/uploads\/2016\/07\/Crise-de-funambulisme-e1467744137225.jpg?fit=1200%2C473&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.donmar.fr\/wp-content\/uploads\/2016\/07\/Crise-de-funambulisme-e1467744137225.jpg?fit=1200%2C473&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.donmar.fr\/wp-content\/uploads\/2016\/07\/Crise-de-funambulisme-e1467744137225.jpg?fit=1200%2C473&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.donmar.fr\/wp-content\/uploads\/2016\/07\/Crise-de-funambulisme-e1467744137225.jpg?fit=1200%2C473&resize=1050%2C600 3x"},"classes":[]},{"id":134,"url":"http:\/\/www.donmar.fr\/index.php\/2016\/02\/15\/la-chrysalide\/","url_meta":{"origin":21,"position":2},"title":"La chrysalide","author":"DonMar","date":"15 f\u00e9vrier 2016","format":false,"excerpt":"Au c\u0153ur de la nuit Je me suis endormie Dans tes bras, Laissant derri\u00e8re moi Les lueurs et les bruits De la vie Je succombe \u00e0 l\u2019oubli. Le temps se d\u00e9lite M\u2019\u00e9gare et dans sa fuite Je te vois, Au loin pr\u00e8s de moi Lov\u00e9s sous les draps Engourdis De\u2026","rel":"","context":"Dans &quot;Chanson&quot;","block_context":{"text":"Chanson","link":"http:\/\/www.donmar.fr\/index.php\/category\/chanson\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.donmar.fr\/wp-content\/uploads\/2016\/07\/La-chrysalide-e1467928650691.jpg?fit=1200%2C506&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.donmar.fr\/wp-content\/uploads\/2016\/07\/La-chrysalide-e1467928650691.jpg?fit=1200%2C506&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.donmar.fr\/wp-content\/uploads\/2016\/07\/La-chrysalide-e1467928650691.jpg?fit=1200%2C506&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.donmar.fr\/wp-content\/uploads\/2016\/07\/La-chrysalide-e1467928650691.jpg?fit=1200%2C506&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.donmar.fr\/wp-content\/uploads\/2016\/07\/La-chrysalide-e1467928650691.jpg?fit=1200%2C506&resize=1050%2C600 3x"},"classes":[]},{"id":58,"url":"http:\/\/www.donmar.fr\/index.php\/2016\/02\/03\/ophelie\/","url_meta":{"origin":21,"position":3},"title":"Oph\u00e9lie","author":"DonMar","date":"3 f\u00e9vrier 2016","format":false,"excerpt":"O vieux po\u00e8te, mille ans se sont \u00e9coul\u00e9s, Et la brise caresse ton p\u00e2le visage En ce matin d\u2019avril, en ses longs voiles couch\u00e9e Tu viens la voir danser sur ce sombre rivage. Le lent fr\u00e9missement des vagues \u00e9veille en toi Le souvenir d\u2019une aube calme et \u00e9ternelle Qui accueillit\u2026","rel":"","context":"Dans &quot;Po\u00e8me&quot;","block_context":{"text":"Po\u00e8me","link":"http:\/\/www.donmar.fr\/index.php\/category\/poeme\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.donmar.fr\/wp-content\/uploads\/2016\/07\/Ophelie-e1467745911931.jpg?fit=1200%2C582&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.donmar.fr\/wp-content\/uploads\/2016\/07\/Ophelie-e1467745911931.jpg?fit=1200%2C582&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.donmar.fr\/wp-content\/uploads\/2016\/07\/Ophelie-e1467745911931.jpg?fit=1200%2C582&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.donmar.fr\/wp-content\/uploads\/2016\/07\/Ophelie-e1467745911931.jpg?fit=1200%2C582&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.donmar.fr\/wp-content\/uploads\/2016\/07\/Ophelie-e1467745911931.jpg?fit=1200%2C582&resize=1050%2C600 3x"},"classes":[]},{"id":43,"url":"http:\/\/www.donmar.fr\/index.php\/2016\/02\/03\/dans-tes-yeux\/","url_meta":{"origin":21,"position":4},"title":"Dans tes yeux","author":"DonMar","date":"3 f\u00e9vrier 2016","format":false,"excerpt":"Dans tes yeux, j\u2019vois plus qu\u2019le reflet De ton absence, de ton indiff\u00e9rence J\u2019te vois pleurer tes r\u00eaves bris\u00e9s Tes espoirs vains bord\u00e9s d\u2019silences. J\u2019t\u2019avais promis tell\u2019ment d\u2019No\u00ebls Pleins d\u2019images pieuses, et de lunes claires Qui s\u2019sont perdus dans tes yeux ciels Dans la nuit d\u2019encre de ton regard fier.\u2026","rel":"","context":"Dans &quot;Chanson&quot;","block_context":{"text":"Chanson","link":"http:\/\/www.donmar.fr\/index.php\/category\/chanson\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.donmar.fr\/wp-content\/uploads\/2016\/07\/dans-tes-yeux-e1467745864264.jpg?fit=1200%2C540&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.donmar.fr\/wp-content\/uploads\/2016\/07\/dans-tes-yeux-e1467745864264.jpg?fit=1200%2C540&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.donmar.fr\/wp-content\/uploads\/2016\/07\/dans-tes-yeux-e1467745864264.jpg?fit=1200%2C540&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.donmar.fr\/wp-content\/uploads\/2016\/07\/dans-tes-yeux-e1467745864264.jpg?fit=1200%2C540&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.donmar.fr\/wp-content\/uploads\/2016\/07\/dans-tes-yeux-e1467745864264.jpg?fit=1200%2C540&resize=1050%2C600 3x"},"classes":[]},{"id":313,"url":"http:\/\/www.donmar.fr\/index.php\/2016\/11\/23\/les-bams-et-les-boums\/","url_meta":{"origin":21,"position":5},"title":"Les bams et les boums","author":"DonMar","date":"23 novembre 2016","format":false,"excerpt":"Ecoute les bams et les boums D\u00e9livrer mon c\u0153ur bless\u00e9 L'amour ce n'est pas attendre En comptant les jours pass\u00e9s Aupr\u00e8s de toi \u00e0 me plaindre D\u2019un bonheur d\u00e9j\u00e0 fan\u00e9. C\u2019est comme un jeu ou enfreindre Les r\u00e8gles \u00e0 ses bons c\u00f4t\u00e9s Un jeu sans \u00e2me \u00e0 contraindre Que des\u2026","rel":"","context":"Dans &quot;Chanson&quot;","block_context":{"text":"Chanson","link":"http:\/\/www.donmar.fr\/index.php\/category\/chanson\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.donmar.fr\/wp-content\/uploads\/2016\/11\/Les-bams-et-les-boums.jpg?fit=1199%2C565&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.donmar.fr\/wp-content\/uploads\/2016\/11\/Les-bams-et-les-boums.jpg?fit=1199%2C565&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.donmar.fr\/wp-content\/uploads\/2016\/11\/Les-bams-et-les-boums.jpg?fit=1199%2C565&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.donmar.fr\/wp-content\/uploads\/2016\/11\/Les-bams-et-les-boums.jpg?fit=1199%2C565&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.donmar.fr\/wp-content\/uploads\/2016\/11\/Les-bams-et-les-boums.jpg?fit=1199%2C565&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"http:\/\/www.donmar.fr\/index.php\/wp-json\/wp\/v2\/posts\/21","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.donmar.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.donmar.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.donmar.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.donmar.fr\/index.php\/wp-json\/wp\/v2\/comments?post=21"}],"version-history":[{"count":8,"href":"http:\/\/www.donmar.fr\/index.php\/wp-json\/wp\/v2\/posts\/21\/revisions"}],"predecessor-version":[{"id":87,"href":"http:\/\/www.donmar.fr\/index.php\/wp-json\/wp\/v2\/posts\/21\/revisions\/87"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.donmar.fr\/index.php\/wp-json\/wp\/v2\/media\/246"}],"wp:attachment":[{"href":"http:\/\/www.donmar.fr\/index.php\/wp-json\/wp\/v2\/media?parent=21"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.donmar.fr\/index.php\/wp-json\/wp\/v2\/categories?post=21"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.donmar.fr\/index.php\/wp-json\/wp\/v2\/tags?post=21"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}